{"id":30707,"date":"2026-01-12T14:53:48","date_gmt":"2026-01-12T13:53:48","guid":{"rendered":"https:\/\/asso.graie.org\/portail\/?p=30707"},"modified":"2026-04-21T11:02:47","modified_gmt":"2026-04-21T09:02:47","slug":"decouvrez-les-principes-du-graie","status":"publish","type":"post","link":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/","title":{"rendered":"D\u00e9couvrez les principes du Graie !"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"246\" src=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-1024x246.png\" alt=\"\" class=\"wp-image-30708\" srcset=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-1024x246.png 1024w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-300x72.png 300w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-768x185.png 768w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-1536x369.png 1536w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/Banner_Graie_Principes-2048x492.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-5 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/Principes_Graie_GIEP.pdf\" style=\"background-color:#0095db\"><strong>T\u00e9l\u00e9charger les principes du Graie<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-3 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/survey.zohopublic.eu\/zs\/OtCA54\" style=\"background-color:#3a2d87\"><strong>J&rsquo;approuve les principes du Graie !<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:66px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La gestion int\u00e9gr\u00e9e et durable des eaux pluviales dans l\u2019am\u00e9nagement s\u2019inscrit dans un contexte en \u00e9volution rapide et complexe : le changement climatique (le trop et le trop peu), la rar\u00e9faction des ressources (eau, sol, \u00e9nergie, mat\u00e9riaux, finances), l\u2019urbanisation croissante et la densification, ainsi que la complexification et l\u2019interconnexion des politiques de la ville.<\/strong><\/h3>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Les principes du Graie portent sur la gestion des eaux pluviales dans l\u2019am\u00e9nagement et visent \u00e0 :<\/p>\n\n\n\n<ul>\n<li>Formaliser et partager <strong>les valeurs du Graie<\/strong><\/li>\n\n\n\n<li>Partager des <strong>retours d\u2019exp\u00e9rience inspirants<\/strong> et contribuer \u00e0 l\u2019\u00e9mulation collective et au <strong>transfert des savoirs et savoir-faire<\/strong><\/li>\n\n\n\n<li>Renforcer la <strong>mise en r\u00e9seau et la visibilit\u00e9 des acteurs<\/strong> qui partagent ces principes et contribuent \u00e0 les mettre en \u0153uvre et \u00e0 les diffuser<\/li>\n<\/ul>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Les principaux enjeux soutenus par les principes sont :<\/strong><\/p>\n\n\n\n<ul>\n<li>G\u00e9rer l\u2019eau de pluie comme une ressource dans une approche transversale<\/li>\n\n\n\n<li>Anticiper la gestion de l\u2019eau dans les projets aux diff\u00e9rentes \u00e9chelles et faire un pas de c\u00f4t\u00e9 pour rechercher des solutions adapt\u00e9es au cas par cas<\/li>\n\n\n\n<li>Contribuer au transfert de connaissances et acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques<\/li>\n<\/ul>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Le d\u00e9ploiement et la mise en \u0153uvre de la bonne gestion des eaux pluviales se joue \u00e0 4 niveaux d\u2019actions compl\u00e9mentaires :<\/strong><\/p>\n\n\n\n<p><mark style=\"background-color:#3a2d87\" class=\"has-inline-color has-white-color\">A.<\/mark> L\u2019\u00e9laboration de politiques et strat\u00e9gies du territoire<br><mark style=\"background-color:#0095db\" class=\"has-inline-color has-white-color\">B.<\/mark> La mise en \u0153uvre d\u2019un cadre d\u2019action favorable \u00e0 l\u2019\u00e9chelle des territoires<br><mark style=\"background-color:#00ffb2;color:#3a2d87\" class=\"has-inline-color\">C.<\/mark> La d\u00e9finition des projets d\u2019am\u00e9nagement et de leurs usages<br><mark style=\"background-color:#d4e9f9;color:#3a2d87\" class=\"has-inline-color\">D.<\/mark> La conception des ouvrages de gestion des eaux pluviales<\/p>\n\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Elle appelle un engagement particulier des acteurs pour promouvoir, faciliter, accompagner ou conduire le changement :<\/strong><\/p>\n\n\n\n<ul>\n<li>Une vision de la bonne gestion des eaux pluviales dans l\u2019am\u00e9nagement<\/li>\n\n\n\n<li>Un engagement des acteurs pour sortir des silos et des sentiers battus<\/li>\n\n\n\n<li>L\u2019ouverture et la mobilisation de comp\u00e9tences multiples et nouvelles<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Il ne s\u2019agit pas d\u2019une r\u00e8gle unique.<\/strong> Ma\u00eetre d\u2019ouvrage, ma\u00eetre d\u2019\u0153uvre, assistants \u00e0 ma\u00eetrise d\u2019ouvrage, entreprises de travaux, etc., chacun agit \u00e0 son niveau, en fonction de ses comp\u00e9tences. C\u2019est l\u00e0 une des grandes richesses de la gestion des eaux pluviales.<\/p>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Nous esp\u00e9rons que ces principes aideront chacun \u00e0 se positionner et faire \u00e9voluer ses pratiques pour une gestion plus durable et int\u00e9gr\u00e9e des eaux pluviales dans l\u2019am\u00e9nagement.<\/mark><\/strong><\/p>\n\n\n\n<div style=\"height:69px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-background\" style=\"background-color:#d4e9f9\"><strong>Vous approuvez les principes du Graie ?<br><\/strong>\u27a1\ufe0f Faites-le nous savoir<strong> <a href=\"https:\/\/survey.zohopublic.eu\/zs\/OtCA54\">en remplissant ce formulaire<\/a><\/strong> d\u00e8s \u00e0 pr\u00e9sent !<br>Plus nous serons nombreux \u00e0 porter ces principes, plus le changement para\u00eetra possible et facile \u00e0 engager pour tous !<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">16 principes du Graie pour la bonne gestion des eaux pluviales<\/h2>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:#3a2d87\" class=\"has-inline-color has-white-color\">A &#8211; L\u2019\u00e9laboration de politiques et strat\u00e9gies du territoire<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-8 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"667\" height=\"729\" src=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_A.png\" alt=\"\" class=\"wp-image-30717\" srcset=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_A.png 667w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_A-274x300.png 274w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>1. AMBITION POLITIQUE &#8211; Formaliser une ambition politique partag\u00e9e &#8211; Clarifier la gouvernance et les responsabilit\u00e9s &#8211; Encourager les exp\u00e9rimentations et innovations<br>2. BASSIN VERSANT &#8211; D\u00e9ployer une vision int\u00e9gr\u00e9e de la ville connect\u00e9e \u00e0 son bassin versant (amont \u2013 aval) &#8211; D\u00e9passer les limites administratives pour s\u2019int\u00e9grer dans la vision bassin versant (territoires et comp\u00e9tences)<br>3. ADAPTATION ANTICIPATION &#8211; Anticiper l\u2019adaptation du territoire au regard des enjeux de l\u2019eau et de la ville &#8211; Rechercher la robustesse face aux changements climatiques<br>4. COOP\u00c9RATION INTERSECTORIELLE &#8211; Mobiliser l\u2019ensemble des acteurs (publics et priv\u00e9s) et les services concern\u00e9s, dans une approche transversale et intersectorielle \u2013 Sensibiliser les citoyens<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les dynamiques d&rsquo;animation du Graie<\/strong><br><\/mark>Pour le Graie, l\u2019intelligence collective, les retours d\u2019exp\u00e9riences et le dialogue inter-acteurs sont les leviers du changement. En r\u00e9unissant collectivit\u00e9s, bureaux d\u2019\u00e9tudes, organismes d\u2019\u00e9tat, gestionnaires avec des formats d\u2019\u00e9change vari\u00e9s, le Graie cr\u00e9e les conditions d\u2019une vision plus int\u00e9gr\u00e9e, plus prospective et partenariale de la gestion de l\u2019eau.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Animer un r\u00e9seau r\u00e9gional \u00ab\u00a0Strat\u00e9gies Cycle de l&rsquo;Eau\u00a0\u00bb<\/summary>\n<p><a href=\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\">3 rencontres d\u00e9but 2026<\/a> pour mettre en place et d\u00e9velopper une dynamique d\u2019\u00e9change et de travail collaboratif. Objectif : outiller les services pour une p\u00e9dagogie vis-\u00e0-vis des nouveaux \u00e9lus sur les enjeux de la transversalit\u00e9 eau\/territoire.<\/p>\n<\/details>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795D\u00e9multiplier les comp\u00e9tences d&rsquo;accompagnement en r\u00e9gion &#8211; L&rsquo;Atelier Ville Perm\u00e9able<\/summary>\n<p>Dynamique engag\u00e9e en 2023 par le Graie, FNE AURA et les CAUE, l\u2019<a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/animations-specifiques\/atelier-ville-permeable\/\">Atelier Ville Perm\u00e9able<\/a> vise \u00e0 cr\u00e9er un r\u00e9seau des structures qui peuvent accompagner les collectivit\u00e9s et ma\u00eetres d\u2019ouvrages pour la sensibilisation, des visites d\u2019op\u00e9rations ou la mise en \u0153uvre de solutions int\u00e9gr\u00e9es de gestion des eaux pluviales, dans une strat\u00e9gie d\u2019adaptation au changement climatique : eaux pluviales, v\u00e9g\u00e9talisation et cadre de vie.<\/p>\n<\/details>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Construire une culture commune de l&rsquo;eau en ville \u00e0 une \u00e9chelle europ\u00e9enne et internationale<\/summary>\n<p>Tous les 3 ans, <a href=\"https:\/\/www.graie-novatech.org\/\">la conf\u00e9rence internationale Novatech<\/a> rassemble scientifiques, d\u00e9cideurs, animateurs, gestionnaires et concepteurs, fran\u00e7ais et internationaux, pour \u00e9changer et partager leurs exp\u00e9riences, et faire \u00e9merger une culture commune sur la gestion de l&rsquo;eau en ville. Rendez-vous du 29 juin au 3 juillet 2026 \u00e0 Lyon !<\/p>\n<\/details>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les ressources Graie<\/strong><br><\/mark>Le Graie publie r\u00e9guli\u00e8rement des documents techniques et de sensibilisation, des synth\u00e8ses, des actes de conf\u00e9rences ainsi que des ouvrages collectifs. Toutes ces productions sont en libre acc\u00e8s sur le site du Graie.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Recueil des Histoires de l&rsquo;Eau<\/summary>\n<p>Les principes du Graie s\u2019inscrivent dans la dynamique engag\u00e9e depuis 2017 avec les Principes de l\u2019IWA pour des territoires \u00ab Eau-Responsables \u00bb. <a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/animations-specifiques\/territoires-eau-responsables\/\">25 territoires de la R\u00e9gion AURA<\/a> ont approuv\u00e9 ces principes et partag\u00e9 leurs r\u00e9cits sur la place de l\u2019eau dans leur territoire, les strat\u00e9gies mises en place et les actions engag\u00e9es pour s\u2019engager vers des territoires \u00ab eau-responsables \u00bb.<\/p>\n<\/details>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Des outils de sensibilisation \u00e0 votre disposition<\/summary>\n<p>Webs\u00e9rie, jeux s\u00e9rieux, illustrations humoristiques et guides synth\u00e9tiques : le Graie vous propose un ensemble d\u2019outils p\u00e9dagogiques pour sensibiliser \u00e0 la gestion int\u00e9gr\u00e9e des eaux pluviales.<\/p>\n\n\n\n<ul>\n<li>Des jeux s\u00e9rieux pour apprendre et r\u00e9fl\u00e9chir ensemble de mani\u00e8re ludique : <a href=\"https:\/\/asso.graie.org\/portail\/jeu-serieux-concertaction-sous-la-pluie\/\">\u00ab\u00a0Concert\u2019action sous la pluie\u00a0\u00bb<\/a>  et la <a href=\"https:\/\/asso.graie.org\/portail\/jeu-serieux-concertaction-sous-la-pluie\/\">\u201cFresque de la Ville Perm\u00e9able\u201d<\/a><\/li>\n\n\n\n<li>Des illustrations r\u00e9alis\u00e9es avec style et humour par Nicolas Journoud : <a href=\"https:\/\/asso.graie.org\/portail\/la-bd-et-pourquoi-pas-un-nouvel-outil-de-sensibilisation-a-la-disposition-de-tous\/\">8 bandes-dessin\u00e9es \u201cEt pourquoi pas\u2026\u201d<\/a> ; \u201c<a href=\"https:\/\/asso.graie.org\/portail\/illustration-de-leau-verticale\/\">Le cheminement vertical de l\u2019eau<\/a>\u201d<\/li>\n\n\n\n<li>Webs\u00e9rie <a href=\"https:\/\/www.graie.org\/eaumelimelo\/\">\u201cM\u00e9li M\u00e9lo \u2013 d\u00e9m\u00ealons les fils de l\u2019eau\u201d<\/a> et illustrations : 16 sujets trait\u00e9s avec humour<\/li>\n\n\n\n<li>Nous avons accompagn\u00e9 nos partenaires dans la r\u00e9daction de guides synth\u00e9tiques et illustr\u00e9s, pour croiser les regards : <a href=\"https:\/\/www.fne-aura.org\/uploads\/2021\/11\/villespermeables_fneaura-web.pdf\">\u201c\u00c0 l\u2019eau les id\u00e9es re\u00e7ues<\/a>\u201d, publi\u00e9 par FNE Auvergne-Rh\u00f4ne-Alpes ; <a href=\"https:\/\/caue69.fr\/Documents\/doc_electronique\/E147.pdf\">\u201cD\u00e9simperm\u00e9abiliser par le v\u00e9g\u00e9tal\u201d<\/a>, r\u00e9alis\u00e9 par le CAUE Rh\u00f4ne M\u00e9tropole<\/li>\n<\/ul>\n<\/details>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:#0095db\" class=\"has-inline-color has-white-color\">B &#8211; La mise en \u0153uvre d\u2019un cadre d\u2019action favorable \u00e0 l\u2019\u00e9chelle des territoires<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-11 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>1. CO-CONSTRUCTION &#8211; \u00c9tablir collectivement des r\u00e8gles int\u00e9grant la transversalit\u00e9 : diversit\u00e9 des objectifs, des fonctions et des secteurs concern\u00e9s<br>2. EMBO\u00ceTEMENT D\u2019\u00c9CHELLES traduisant l\u2019articulation des diff\u00e9rentes politiques publiques (zonages et PLU), programmes et plans de gestion &#8211; Garantir l\u2019articulation des diff\u00e9rents plans et sch\u00e9mas relatifs \u00e0 l\u2019eau (assainissement, SAGE, PPRI\u2026)<br>3. R\u00c8GLES GIEP &#8211; Gestion Int\u00e9gr\u00e9e des Eaux Pluviales &#8211; \u00c9tablir des r\u00e8gles GIEP favorisant la gestion \u00e0 la source et les solutions fond\u00e9es sur la nature &#8211; Int\u00e9grer les diff\u00e9rentes dimensions de la GIEP : niveaux de service, ouverte \u00e0 la diversit\u00e9 des solutions, dans les documents de planification<br>4. ACCOMPAGNEMENT \u2013 D\u00e9velopper des moyens pour accompagner les changements de paradigme et de pratiques : sensibiliser l\u2019ensemble des acteurs, y compris les usagers, communiquer, expliquer et accompagner la mise en \u0153uvre des principes propos\u00e9s<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"667\" height=\"729\" src=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_B.png\" alt=\"\" class=\"wp-image-30754\" srcset=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_B.png 667w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_B-274x300.png 274w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les dynamiques d&rsquo;animation du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Animer le R\u00e9seau francophone des animateurs eaux pluviales<\/summary>\n<p>Cr\u00e9\u00e9 en 2019, le <a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/animations-specifiques\/reseau-animateurs-eaux-pluviales\/\" class=\"broken_link\">R\u00e9seau francophone des animateurs eaux pluviales (RFATEP)<\/a> r\u00e9unit une communaut\u00e9 de 250 animateurs et de charg\u00e9s de mission engag\u00e9s dans la gestion int\u00e9gr\u00e9e des eaux pluviales. Le r\u00e9seau favorise le partage d\u2019exp\u00e9riences et de ressources \u00e0 travers des rencontres nationales (le 29 juin \u00e0 Lyon), des webinaires et des \u00e9changes continus entre ses membres notamment gr\u00e2ce \u00e0 la plateforme collaborative \u201cExpertises Territoires\u201d du Cerema. Rejoignez-nous !<\/p>\n<\/details>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Former : Parcours de formation \u00ab Gestion des eaux pluviales \u00e0 la source \u00bb<\/summary>\n<p>En suivant le module <a href=\"https:\/\/asso.graie.org\/portail\/diffusion\/formations\/\">\u00ab Du projet d\u2019am\u00e9nagement \u00e0 la strat\u00e9gie \u00bb<\/a>, vous b\u00e9n\u00e9ficierez de l\u2019expertise de scientifiques, de collectivit\u00e9s et de ma\u00eetres d\u2019\u0153uvre du r\u00e9seau du Graie, qui \u0153uvrent depuis plus de 40 ans pour mieux comprendre et mieux g\u00e9rer les eaux pluviales dans les strat\u00e9gies de territoire et les projets d\u2019am\u00e9nagement.<\/p>\n<\/details>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les ressources du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795D\u00e9finition du m\u00e9tier \u00ab\u00a0Animateur Eaux Pluviales\u00a0\u00bb<\/summary>\n<p>En 2023, le RFATEP produit le document <a href=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2023\/12\/Profils_et_missions_animateur_EP.pdf\">\u201cProfils et missions de l\u2019animateur Eaux Pluviales\u201d<\/a> qui permet de d\u00e9finir ce m\u00e9tier \u00e9mergent et faciliter la mise en place et le d\u00e9ploiement de moyens humains adapt\u00e9s au sein des collectivit\u00e9s.<\/p>\n<\/details>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Des guides pour faciliter l\u2019int\u00e9gration des eaux pluviales dans l\u2019urbanisme<\/summary>\n<ul>\n<li><a href=\"http:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/guideepurba.pdf\">Guide eaux pluviales et urbanisme<\/a> : ce guide pr\u00e9sente l\u2019ensemble des outils r\u00e8glementaires dans lesquels peuvent \u00eatre introduits des \u00e9l\u00e9ments de cadrage relatifs \u00e0 la gestion des eaux pluviales, qu\u2019ils rel\u00e8vent de la gestion de l\u2019eau ou de l\u2019am\u00e9nagement.<\/li>\n\n\n\n<li style=\"font-size:18px\"><a href=\"http:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/guideSDGEP.pdf\">Guide sch\u00e9ma de gestion des eaux pluviales :<\/a> dans la continuit\u00e9 du premier guide, cet outil vise \u00e0 fournir des \u00e9l\u00e9ments pour accompagner la r\u00e9alisation de sch\u00e9mas de gestion des eaux pluviales, les questions \u00e0 se poser, \u00e0 l\u2019appui d\u2019exp\u00e9riences contrast\u00e9es.<\/li>\n<\/ul>\n<\/details>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Des outils pour aider \u00e0 d\u00e9finir un service GEPU<\/summary>\n<p>La d\u00e9finition de la comp\u00e9tence \u00ab Gestion des eaux pluviales urbaines \u00bb (GEPU) et du service qui en assure les missions soul\u00e8vent de nombreux questionnements de la part des collectivit\u00e9s, de leurs prestataires et des partenaires qui les accompagnent. Pour aider \u00e0 y r\u00e9pondre, les Groupes de travail du Graie ont d\u00e9velopp\u00e9 plusieurs outils.<\/p>\n\n\n\n<ul>\n<li><a href=\"https:\/\/asso.graie.org\/portail\/competencegestioneauxpluvialesurbaines-ouvragesmissions-mai19\/\">Grilles d\u2019aide \u00e0 la d\u00e9finition de la comp\u00e9tence GEPU<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/asso.graie.org\/portail\/trame-pour-lelaboration-du-cahier-des-clauses-techniques-particulieres-c-c-t-p-dune-etude-prealable-au-transfert-de-la-competence-eau-potable-assainissement-gestion-des-eaux-pluvi\/\">Trame pour l\u2019\u00e9laboration d\u2019un Cahier des clauses techniques particuli\u00e8res<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/asso.graie.org\/portail\/transfert-competences-chronogramme\/\">Recommandations de chronogramme pour le transfert de comp\u00e9tences<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/GRAIE_OutilsSupportsPedagogiques_Competences.pdf\">Bo\u00eete \u00e0 outils pour le transfert<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Le Graie met \u00e9galement \u00e0 disposition des \u00ab Retours d\u2019exp\u00e9riences \u00bb issus des nombreux \u00e9v\u00e9nements qu\u2019il organise.<\/p>\n<\/details>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:#00ffb2;color:#3a2d87\" class=\"has-inline-color\">C &#8211; La d\u00e9finition des projets d\u2019am\u00e9nagement et de leurs usages<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-14 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"667\" height=\"729\" src=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_C.png\" alt=\"\" class=\"wp-image-30777\" srcset=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_C.png 667w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_C-274x300.png 274w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>1. RESPECT DES SP\u00c9CIFICIT\u00c9S &#8211; Lire le paysage, respecter le cycle naturel de l\u2019eau et la topographie du site (actuel et historique), et ce, d\u00e8s le plan masse<br>2. ANTICIPATION &#8211; Anticiper les effets du changement climatique \u2013 Anticiper les parcours de l\u2019eau en amont de la conception des projets, et notamment adapter les formes urbaines \u00e0 la gestion de l\u2019eau (perm\u00e9abilit\u00e9, connexion au sol, axes d\u2019\u00e9coulement) &#8211; Anticiper et mobiliser les futurs usagers et exploitants<br>3. SOBRI\u00c9T\u00c9 (\u00c9CONOMISER) &#8211; Prioriser des am\u00e9nagements peu techniques, sobres et utilisant les pouvoirs du sol et du v\u00e9g\u00e9tal \u2013 Eviter l\u2019imperm\u00e9abilisation et la canalisation des eaux &#8211; Valoriser les eaux pluviales comme une ressource \u2013 Renforcer la circularit\u00e9 locale de l\u2019eau &#8211; Privil\u00e9gier des am\u00e9nagements surfaciques multiusages et multifonctionnels<br>4. COMBINAISON DES SOLUTIONS &#8211; Combiner diff\u00e9rentes solutions, assurer une continuit\u00e9 fonctionnelle entre ouvrages publics et priv\u00e9s face aux diff\u00e9rents \u00e9v\u00e9nements climatiques<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les dynamiques d&rsquo;animation du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Animer le Groupe de travail \u00ab Eaux pluviales et Am\u00e9nagement \u00bb<\/summary>\n<p>Ce <a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/gt-eaux-pluviales\/\">groupe de travail<\/a> r\u00e9gional r\u00e9unit 3 fois par an des experts et techniciens ayant des approches compl\u00e9mentaires et a pour objectif de promouvoir le d\u00e9veloppement de strat\u00e9gies, d\u2019op\u00e9rations et de solutions exemplaires en mati\u00e8re de gestion des eaux pluviales. Ensemble, ils \u00e9changent, visitent et s\u2019attachent \u00e0 proposer des outils pour am\u00e9liorer et faciliter la bonne gestion des eaux pluviales dans l\u2019am\u00e9nagement.<\/p>\n<\/details>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Favoriser la coop\u00e9ration op\u00e9rationnelle des acteurs de l&rsquo;am\u00e9nagement <\/summary>\n<p>Le <a href=\"https:\/\/asso.graie.org\/portail\/nouveau-partenariat-vad-graie\/\">partenariat avec Ville &amp; Am\u00e9nagement Durable<\/a> concr\u00e9tise la volont\u00e9 conjointe de nos deux associations d\u2019acculturer et favoriser la coop\u00e9ration op\u00e9rationnelle des acteurs de l\u2019am\u00e9nagement, de l\u2019urbanisme et de l\u2019eau, afin de croiser les regards et s\u2019inscrire collectivement dans des d\u00e9marches de projets plus int\u00e9gr\u00e9es. Ensemble, nous \u00e9laborons une r\u00e9flexion et des \u00e9v\u00e9nements centr\u00e9s sur la place de l\u2019eau face aux enjeux de r\u00e9silience, de biodiversit\u00e9 en ville et de surchauffe urbaine.<\/p>\n<\/details>\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Former les ing\u00e9nieurs et techniciens d&rsquo;aujourd&rsquo;hui et de demain<\/summary>\n<p>Gr\u00e2ce au module \u00ab Concevoir et \u00e9valuer les projets \u00bb, les maitres d\u2019ouvrages, AMO et ma\u00eetres d\u2019\u0153uvre qui d\u00e9marrent sur le sujet ou qui int\u00e8grent la gestion des eaux pluviales \u00e0 d\u2019autres enjeux et objectifs sauront mieux anticiper les principes, les co\u00fbts et temps des \u00e9tudes pour optimiser les projets.<\/p>\n<\/details>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les ressources du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Observatoire des op\u00e9rations exemplaires pour la gestion des eaux pluviales<\/summary>\n<p>Port\u00e9 par le Groupe de Travail Eaux Pluviales, <a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/techniques-alternatives\/\">cet observatoire<\/a> recense pr\u00e8s de 400 am\u00e9nagements r\u00e9alis\u00e9s en Auvergne-Rh\u00f4ne-Alpes en faveur de la gestion \u00e0 la source des eaux pluviales, dont 90 font l\u2019objet de fiches d\u00e9taill\u00e9es. La carte, les photos et les fiches sont disponibles sur le site du Graie.<\/p>\n<\/details>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795La frise des temps de l\u2019am\u00e9nagement pour la bonne gestion des eaux pluviales<\/summary>\n<p><a href=\"https:\/\/asso.graie.org\/portail\/la-frise-des-temps-de-lamenagement-pour-la-gestion-des-eaux-pluviales\/\">Sur la base d\u2019une trame chronologique<\/a>, cet outil guide le ma\u00eetre d\u2019ouvrage sur la prise en compte des eaux pluviales dans les temps forts de son projet : la vision strat\u00e9gique, la cr\u00e9ation du projet, sa r\u00e9alisation et enfin son exploitation voire sa r\u00e9habilitation.<\/p>\n<\/details>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:#d4e9f9;color:#3a2d87\" class=\"has-inline-color\">D &#8211; La conception des ouvrages de gestion des eaux pluviales<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-17 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>1. ANTICIPATION &#8211; Anticiper l\u2019entretien et la maintenance par une conception collaborative, une formation des services et la sensibilisation des usagers \u2013 Respecter les objectifs de plurifonctionnalit\u00e9<br>2. DIMENSIONNEMENT &#8211; Dimensionner les ouvrages et am\u00e9nagements en int\u00e9grant les diff\u00e9rents niveaux de service et le changement climatique<br>3. R\u00c9ALISATION &#8211; \u00c9tablir le cadre d\u2019une r\u00e9alisation pr\u00e9cautionneuse et adapt\u00e9e \u2013 Accompagner les changements de pratiques<br>4. SUIVI ET ADAPTATION &#8211; Mettre en \u0153uvre un suivi et une gestion patrimoniale active (performances, r\u00e9f\u00e9rencement SIG)<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"667\" height=\"729\" src=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_D.png\" alt=\"\" class=\"wp-image-30778\" srcset=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_D.png 667w, https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/principes_Graie_D-274x300.png 274w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les dynamiques d&rsquo;animation du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Animer un dispositif de recherche ancr\u00e9 dans les territoires et valoriser les r\u00e9sultats<\/summary>\n<p><a href=\"https:\/\/www.othu.org\/\">L\u2019OTHU \u2013 Observatoire de Terrain en Hydrologie Urbaine<\/a> est un laboratoire de recherche hors murs ancr\u00e9 sur la r\u00e9gion lyonnaise. Depuis 25 ans, ce dispositif pluridisciplinaire porte sur l\u2019observation des rejets urbains et de leurs impacts sur les milieux r\u00e9cepteurs, notamment par temps de pluie. L\u2019objectif est de comprendre et proposer de nouvelles solutions de conception et de gestion de l\u2019assainissement.<\/p>\n<\/details>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795\u00c9changer entre France et Qu\u00e9bec- Les webinaires Ville perm\u00e9able<\/summary>\n<p>Depuis 2020, le Graie propose un <a href=\"https:\/\/www.youtube.com\/watch?v=JPL5ZmoQBh8&amp;list=PL8wU9ui8zEy37hO5PqqqeLhpN_Zit4c4X\">rendez-vous annuel dans le cadre d\u2019un partenariat France-Qu\u00e9bec<\/a> sur la ville perm\u00e9able : des conceptions diff\u00e9rentes des deux c\u00f4t\u00e9s de l\u2019atlantique et un enrichissement certains \u00e0 mettre ces projets, d\u00e9marches, r\u00e9alisations, outils et perceptions en perspective le temps d\u2019un \u00e9change de vive voix !<\/p>\n<\/details>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Former &#8211; Formation continue \u00ab Dimensionner les ouvrages et analyser leur fonctionnement \u00bb<\/summary>\n<p style=\"font-size:18px\"><a href=\"https:\/\/asso.graie.org\/portail\/formation-continue-gestion-des-eaux-pluviales-a-la-source-dimensionner-les-ouvrages\/\">Ce module 3 du parcours \u00ab Gestion des Eaux Pluviales \u00e0 la source \u00bb<\/a> permet aux techniciens et ing\u00e9nieurs charg\u00e9s de concevoir des am\u00e9nagements de consolider et approfondir leurs savoirs et savoir-faire en hydrologie urbaine et utiliser les outils de mod\u00e9lisation adapt\u00e9s.<\/p>\n<\/details>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Les ressources du Graie<\/strong><\/mark><\/p>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Les productions de l\u2019OTHU<\/summary>\n<p>Au-del\u00e0 des publications acad\u00e9miques, l\u2019OTHU valorise ses r\u00e9sultats \u00e0 travers des documents de synth\u00e8se, fiches techniques et guides, \u00e0 la disposition de de tous les acteurs de l\u2019am\u00e9nagement du territoire et de la gestion de l\u2019eau.<\/p>\n\n\n\n<ul>\n<li><a href=\"https:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/OUVRAGE-OTHU\/OTHU-GRAIE_Gestion des eaux pluviales en ville_2022_complet.pdf\">Gestion des eaux pluviales en ville | 20 ans de recherche au service de l\u2019action<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.othu.org\/pdfothu\/fiches\/fichetot2012repro.pdf\">26 fiches techniques sur la m\u00e9trologie et la compr\u00e9hension du fonctionnement des ouvrages<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/ANRFROG-OTHU-GRAIE-GUIDE-OPERATIONNEL-NappeBassinsEaupluviale-2021VF.pdf\">Guide op\u00e9rationnel programme FROG \u2013 Eaux pluviales et nappe phr\u00e9atique<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/actesyntheses\/GRAIE-L4B-MicroMegas-TApollutions-VFIN.pdf\">Synth\u00e8se op\u00e9rationnelle MICROMEGAS | Gestion des eaux pluviales &amp; Micropolluants<\/a><\/li>\n<\/ul>\n<\/details>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Fiches \u00ab\u00a0Vrai ou Faux &#8211; Les techniques alternatives : risques r\u00e9els et avantages\u00a0\u00bb <\/summary>\n<p><a href=\"http:\/\/www.graie.org\/graie\/graiedoc\/reseaux\/pluvial\/TA_FreinsAvantages\/EauxPluviales-outil-techniquesalternatives-V2-nov2016.pdf\">Des outils simples <\/a>pour donner les arguments afin de lever certaines des r\u00e9ticences et freins souvent avanc\u00e9s face \u00e0 des projets qui veulent sortir des sentiers battus : l\u2019infiltration, le colmatage, la pollution, les risques, etc.<\/p>\n<\/details>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<details class=\"wp-block-details\" style=\"font-size:18px\"><summary>\u2795Analyse et comparaison des co\u00fbts \u00ab\u00a0La gestion \u00e0 la source des eaux pluviales &#8211; Est-ce efficace ? Est-ce plus cher ?\u00a0\u00bb<\/summary>\n<p>Une \u00e9tude de cas, r\u00e9alis\u00e9e en partenariat avec l\u2019INSA Lyon, compare <a href=\"http:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/Eaux_pluviales_gestion_source_modelisation.pdf\">3 sc\u00e9narios avec des degr\u00e9s de d\u00e9centralisation croissants<\/a>, inspir\u00e9s d\u2019un cas r\u00e9el de ZAC (r\u00e9seau et bassin, noues et\/ou toitures v\u00e9g\u00e9talis\u00e9es). <\/p>\n\n\n\n<p>Les co\u00fbts des diff\u00e9rents sc\u00e9narios ont \u00e9t\u00e9 identifi\u00e9s et compar\u00e9s : <a href=\"http:\/\/www.graie.org\/graie\/graiedoc\/doc_telech\/Eaux_pluviales_gestion_source_cout_sept18.pdf\">une grille d\u2019analyse <\/a>permet d\u2019\u00e9valuer les diff\u00e9rents postes de charge, en investissement, entretien et maintenance, et leur r\u00e9partition entre les diff\u00e9rents acteurs.<\/p>\n<\/details>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Contexte<\/h2>\n\n\n\n<p><br><strong>Les principes du Graie pour la bonne gestion des eaux pluviales dans l\u2019am\u00e9nagement s\u2019inscrivent dans la dynamique engag\u00e9e aux c\u00f4t\u00e9s de l\u2019IWA<\/strong> <a href=\"https:\/\/asso.graie.org\/portail\/animationregionale\/animations-specifiques\/territoires-eau-responsables\/\">avec les principes pour des territoires \u00ab Eau-responsables \u00bb <\/a>sur lesquels 25 territoires de la R\u00e9gion Auvergne Rh\u00f4ne Alpes se sont engag\u00e9s depuis 2017.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Le Graie a \u00e9t\u00e9 cr\u00e9\u00e9 en 1985 pour favoriser le d\u00e9veloppement des connaissances et l\u2019am\u00e9lioration des pratiques pour la gestion int\u00e9gr\u00e9e et durable de l\u2019eau dans la ville.<\/strong> La gestion des eaux pluviales et l\u2019hydrologie urbaine sont des th\u00e9matiques phares port\u00e9es depuis sa cr\u00e9ation.<\/p>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La gestion int\u00e9gr\u00e9e est un r\u00e9el changement de paradigme au regard de la vision traditionnelle et historique de la gestion des eaux pluviales et de l\u2019assainissement, de l\u2019urbanisme et de l\u2019am\u00e9nagement des villes.<\/p>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Ces principes ont largement \u00e9volu\u00e9 au cours des quatre d\u00e9cennies d\u2019existence du Graie, au regard des connaissances nouvelles, des contextes et des enjeux nouveaux et de la sensibilit\u00e9 des acteurs des politiques publiques \u00e0 la place et la valeur de l\u2019eau dans l\u2019am\u00e9nagement. Cependant, elle reste consid\u00e9r\u00e9e comme une solution nouvelle appelant un changement des pratiques.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Faire valoir la diversit\u00e9 et la quantit\u00e9 d\u2019acteurs engag\u00e9s sur ces principes (maitres d\u2019ouvrages, maitres d\u2019\u0153uvres, entreprises, chercheurs) est une fa\u00e7on de montrer que la transition vers une gestion plus durable et int\u00e9gr\u00e9e des eaux pluviales est bien engag\u00e9e.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Illustrations : Nicolas Journoud<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>16 principes du Graie pour la bonne gestion des eaux pluviales.  La gestion int\u00e9gr\u00e9e et durable des eaux pluviales dans l\u2019am\u00e9nagement s\u2019inscrit dans un contexte en \u00e9volution rapide et complexe : le changement climatique (le trop et le trop peu), la rar\u00e9faction des ressources (eau, sol, \u00e9nergie, mat\u00e9riaux, finances), l\u2019urbanisation croissante et la densification, ainsi que la complexification et l\u2019interconnexion des politiques de la ville.<\/p>\n","protected":false},"author":16,"featured_media":30835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[24,70,569,1512,28],"tags":[221],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9couvrez les principes du Graie ! | Graie<\/title>\n<meta name=\"description\" content=\"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9couvrez les principes du Graie ! | Graie\" \/>\n<meta property=\"og:description\" content=\"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\" \/>\n<meta property=\"og:site_name\" content=\"Graie\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T13:53:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T09:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/vignette_principes_Graie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maureen Carpentier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@asso_graie\" \/>\n<meta name=\"twitter:site\" content=\"@asso_graie\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maureen Carpentier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\"},\"author\":{\"name\":\"Maureen Carpentier\",\"@id\":\"https:\/\/asso.graie.org\/portail\/#\/schema\/person\/486e14d091ff09d12f2b31bad560eb4f\"},\"headline\":\"D\u00e9couvrez les principes du Graie !\",\"datePublished\":\"2026-01-12T13:53:48+00:00\",\"dateModified\":\"2026-04-21T09:02:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\"},\"wordCount\":3104,\"publisher\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/#organization\"},\"keywords\":[\"principes\"],\"articleSection\":[\"Actu Graie\",\"Eau dans la ville\",\"Eaux pluviales\",\"Mettre en avant - page d'accueil\",\"Toute l'actualit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\",\"url\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\",\"name\":\"D\u00e9couvrez les principes du Graie ! | Graie\",\"isPartOf\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/#website\"},\"datePublished\":\"2026-01-12T13:53:48+00:00\",\"dateModified\":\"2026-04-21T09:02:47+00:00\",\"description\":\"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.\",\"breadcrumb\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/asso.graie.org\/portail\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9couvrez les principes du Graie !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/asso.graie.org\/portail\/#website\",\"url\":\"https:\/\/asso.graie.org\/portail\/\",\"name\":\"Graie\",\"description\":\"P\u00f4le Eau et Territoires\",\"publisher\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/asso.graie.org\/portail\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/asso.graie.org\/portail\/#organization\",\"name\":\"Le Graie\",\"url\":\"https:\/\/asso.graie.org\/portail\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/asso.graie.org\/portail\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2021\/12\/Logotype-Graie.png\",\"contentUrl\":\"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2021\/12\/Logotype-Graie.png\",\"width\":1890,\"height\":1181,\"caption\":\"Le Graie\"},\"image\":{\"@id\":\"https:\/\/asso.graie.org\/portail\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr.linkedin.com\/company\/graie?trk=top_nav_home\",\"https:\/\/www.youtube.com\/channel\/UCZQk0Tt7upYwERYNdDIZqLQ\",\"https:\/\/twitter.com\/asso_graie\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/asso.graie.org\/portail\/#\/schema\/person\/486e14d091ff09d12f2b31bad560eb4f\",\"name\":\"Maureen Carpentier\",\"url\":\"https:\/\/asso.graie.org\/portail\/author\/juliettecasanova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9couvrez les principes du Graie ! | Graie","description":"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9couvrez les principes du Graie ! | Graie","og_description":"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.","og_url":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/","og_site_name":"Graie","article_published_time":"2026-01-12T13:53:48+00:00","article_modified_time":"2026-04-21T09:02:47+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2026\/01\/vignette_principes_Graie.png","type":"image\/png"}],"author":"Maureen Carpentier","twitter_card":"summary_large_image","twitter_creator":"@asso_graie","twitter_site":"@asso_graie","twitter_misc":{"\u00c9crit par":"Maureen Carpentier","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#article","isPartOf":{"@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/"},"author":{"name":"Maureen Carpentier","@id":"https:\/\/asso.graie.org\/portail\/#\/schema\/person\/486e14d091ff09d12f2b31bad560eb4f"},"headline":"D\u00e9couvrez les principes du Graie !","datePublished":"2026-01-12T13:53:48+00:00","dateModified":"2026-04-21T09:02:47+00:00","mainEntityOfPage":{"@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/"},"wordCount":3104,"publisher":{"@id":"https:\/\/asso.graie.org\/portail\/#organization"},"keywords":["principes"],"articleSection":["Actu Graie","Eau dans la ville","Eaux pluviales","Mettre en avant - page d'accueil","Toute l'actualit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/","url":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/","name":"D\u00e9couvrez les principes du Graie ! | Graie","isPartOf":{"@id":"https:\/\/asso.graie.org\/portail\/#website"},"datePublished":"2026-01-12T13:53:48+00:00","dateModified":"2026-04-21T09:02:47+00:00","description":"\u00c0 travers ses 16 principes, le Graie soutient des enjeux majeurs : g\u00e9rer l\u2019eau de pluie comme une v\u00e9ritable ressource dans une approche transversale, anticiper sa gestion \u00e0 toutes les \u00e9chelles des projets en prenant le recul n\u00e9cessaire pour concevoir des solutions adapt\u00e9es \u00e0 chaque contexte, et favoriser le partage des connaissances afin d\u2019acc\u00e9l\u00e9rer l\u2019\u00e9volution des pratiques.","breadcrumb":{"@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/asso.graie.org\/portail\/decouvrez-les-principes-du-graie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asso.graie.org\/portail\/"},{"@type":"ListItem","position":2,"name":"D\u00e9couvrez les principes du Graie !"}]},{"@type":"WebSite","@id":"https:\/\/asso.graie.org\/portail\/#website","url":"https:\/\/asso.graie.org\/portail\/","name":"Graie","description":"P\u00f4le Eau et Territoires","publisher":{"@id":"https:\/\/asso.graie.org\/portail\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asso.graie.org\/portail\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asso.graie.org\/portail\/#organization","name":"Le Graie","url":"https:\/\/asso.graie.org\/portail\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asso.graie.org\/portail\/#\/schema\/logo\/image\/","url":"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2021\/12\/Logotype-Graie.png","contentUrl":"https:\/\/asso.graie.org\/portail\/wp-content\/uploads\/2021\/12\/Logotype-Graie.png","width":1890,"height":1181,"caption":"Le Graie"},"image":{"@id":"https:\/\/asso.graie.org\/portail\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/graie?trk=top_nav_home","https:\/\/www.youtube.com\/channel\/UCZQk0Tt7upYwERYNdDIZqLQ","https:\/\/twitter.com\/asso_graie"]},{"@type":"Person","@id":"https:\/\/asso.graie.org\/portail\/#\/schema\/person\/486e14d091ff09d12f2b31bad560eb4f","name":"Maureen Carpentier","url":"https:\/\/asso.graie.org\/portail\/author\/juliettecasanova\/"}]}},"_links":{"self":[{"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/posts\/30707"}],"collection":[{"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/comments?post=30707"}],"version-history":[{"count":133,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/posts\/30707\/revisions"}],"predecessor-version":[{"id":31488,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/posts\/30707\/revisions\/31488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/media\/30835"}],"wp:attachment":[{"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/media?parent=30707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/categories?post=30707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asso.graie.org\/portail\/wp-json\/wp\/v2\/tags?post=30707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}